{"id":179,"date":"2022-07-12T10:54:46","date_gmt":"2022-07-12T17:54:46","guid":{"rendered":"https:\/\/eliteveinclinic.com\/?post_type=locations&#038;p=179"},"modified":"2026-07-11T08:02:21","modified_gmt":"2026-07-11T15:02:21","slug":"varices-flagstaff","status":"publish","type":"locations","link":"https:\/\/eliteveinclinic.com\/es\/locations\/varicose-veins-flagstaff\/","title":{"rendered":"Flagstaff"},"content":{"rendered":"","protected":false},"featured_media":3118,"template":"","tags":[],"class_list":["post-179","locations","type-locations","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flagstaff Varicose Vein Specialist | Elite Vein Clinic<\/title>\n<meta name=\"description\" content=\"Trust in expert, minimally invasive care at our vein clinic in Flagstaff. Our advanced vein treatments in Flagstaff relieve pain and restore confidence.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eliteveinclinic.com\/es\/lugares\/varices-flagstaff\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flagstaff Varicose Vein Specialist | Elite Vein Clinic\" \/>\n<meta property=\"og:description\" content=\"Trust in expert, minimally invasive care at our vein clinic in Flagstaff. Our advanced vein treatments in Flagstaff relieve pain and restore confidence.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eliteveinclinic.com\/es\/lugares\/varices-flagstaff\/\" \/>\n<meta property=\"og:site_name\" content=\"Elite Vein Clinic\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-11T15:02:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eliteveinclinic.com\/wp-content\/uploads\/2025\/03\/bhyqcf8xjmgy87mjjkmi.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/varicose-veins-flagstaff\\\/\",\"url\":\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/varicose-veins-flagstaff\\\/\",\"name\":\"Flagstaff Varicose Vein Specialist | Elite Vein Clinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/varicose-veins-flagstaff\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/varicose-veins-flagstaff\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eliteveinclinic.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/bhyqcf8xjmgy87mjjkmi.webp\",\"datePublished\":\"2022-07-12T17:54:46+00:00\",\"dateModified\":\"2026-07-11T15:02:21+00:00\",\"description\":\"Trust in expert, minimally invasive care at our vein clinic in Flagstaff. Our advanced vein treatments in Flagstaff relieve pain and restore confidence.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/varicose-veins-flagstaff\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/varicose-veins-flagstaff\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/varicose-veins-flagstaff\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eliteveinclinic.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/bhyqcf8xjmgy87mjjkmi.webp\",\"contentUrl\":\"https:\\\/\\\/eliteveinclinic.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/bhyqcf8xjmgy87mjjkmi.webp\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/varicose-veins-flagstaff\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eliteveinclinic.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Locations\",\"item\":\"https:\\\/\\\/eliteveinclinic.com\\\/locations\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Flagstaff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/\",\"name\":\"Elite Vein Clinic\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/#organization\",\"name\":\"Elite Vein Clinic\",\"url\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eliteveinclinic.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/new-logo-300-x-80.png\",\"contentUrl\":\"https:\\\/\\\/eliteveinclinic.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/new-logo-300-x-80.png\",\"width\":300,\"height\":80,\"caption\":\"Elite Vein Clinic\"},\"image\":{\"@id\":\"https:\\\/\\\/eliteveinclinic.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flagstaff Varicose Vein Specialist | Elite Vein Clinic","description":"Conf\u00ede en el cuidado experto, m\u00ednimamente invasivo en nuestra cl\u00ednica de vena en Flagstaff. Nuestros avanzados tratamientos venosos en Flagstaff alivian el dolor y devuelven la confianza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eliteveinclinic.com\/es\/lugares\/varices-flagstaff\/","og_locale":"es_ES","og_type":"article","og_title":"Flagstaff Varicose Vein Specialist | Elite Vein Clinic","og_description":"Trust in expert, minimally invasive care at our vein clinic in Flagstaff. Our advanced vein treatments in Flagstaff relieve pain and restore confidence.","og_url":"https:\/\/eliteveinclinic.com\/es\/lugares\/varices-flagstaff\/","og_site_name":"Elite Vein Clinic","article_modified_time":"2026-07-11T15:02:21+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/eliteveinclinic.com\/wp-content\/uploads\/2025\/03\/bhyqcf8xjmgy87mjjkmi.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eliteveinclinic.com\/locations\/varicose-veins-flagstaff\/","url":"https:\/\/eliteveinclinic.com\/locations\/varicose-veins-flagstaff\/","name":"Flagstaff Varicose Vein Specialist | Elite Vein Clinic","isPartOf":{"@id":"https:\/\/eliteveinclinic.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eliteveinclinic.com\/locations\/varicose-veins-flagstaff\/#primaryimage"},"image":{"@id":"https:\/\/eliteveinclinic.com\/locations\/varicose-veins-flagstaff\/#primaryimage"},"thumbnailUrl":"https:\/\/eliteveinclinic.com\/wp-content\/uploads\/2025\/03\/bhyqcf8xjmgy87mjjkmi.webp","datePublished":"2022-07-12T17:54:46+00:00","dateModified":"2026-07-11T15:02:21+00:00","description":"Conf\u00ede en el cuidado experto, m\u00ednimamente invasivo en nuestra cl\u00ednica de vena en Flagstaff. Nuestros avanzados tratamientos venosos en Flagstaff alivian el dolor y devuelven la confianza.","breadcrumb":{"@id":"https:\/\/eliteveinclinic.com\/locations\/varicose-veins-flagstaff\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eliteveinclinic.com\/locations\/varicose-veins-flagstaff\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eliteveinclinic.com\/locations\/varicose-veins-flagstaff\/#primaryimage","url":"https:\/\/eliteveinclinic.com\/wp-content\/uploads\/2025\/03\/bhyqcf8xjmgy87mjjkmi.webp","contentUrl":"https:\/\/eliteveinclinic.com\/wp-content\/uploads\/2025\/03\/bhyqcf8xjmgy87mjjkmi.webp","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/eliteveinclinic.com\/locations\/varicose-veins-flagstaff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eliteveinclinic.com\/"},{"@type":"ListItem","position":2,"name":"Locations","item":"https:\/\/eliteveinclinic.com\/locations\/"},{"@type":"ListItem","position":3,"name":"Flagstaff"}]},{"@type":"WebSite","@id":"https:\/\/eliteveinclinic.com\/es\/#website","url":"https:\/\/eliteveinclinic.com\/es\/","name":"Cl\u00ednica Elite Vein","description":"","publisher":{"@id":"https:\/\/eliteveinclinic.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eliteveinclinic.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eliteveinclinic.com\/es\/#organization","name":"Cl\u00ednica Elite Vein","url":"https:\/\/eliteveinclinic.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eliteveinclinic.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/eliteveinclinic.com\/wp-content\/uploads\/2022\/07\/new-logo-300-x-80.png","contentUrl":"https:\/\/eliteveinclinic.com\/wp-content\/uploads\/2022\/07\/new-logo-300-x-80.png","width":300,"height":80,"caption":"Elite Vein Clinic"},"image":{"@id":"https:\/\/eliteveinclinic.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eliteveinclinic.com\/es\/wp-json\/wp\/v2\/locations\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eliteveinclinic.com\/es\/wp-json\/wp\/v2\/locations"}],"about":[{"href":"https:\/\/eliteveinclinic.com\/es\/wp-json\/wp\/v2\/types\/locations"}],"wp:attachment":[{"href":"https:\/\/eliteveinclinic.com\/es\/wp-json\/wp\/v2\/media?parent=179"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eliteveinclinic.com\/es\/wp-json\/wp\/v2\/tags?post=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}